{"id":2436,"date":"2023-07-18T07:41:53","date_gmt":"2023-07-18T07:41:53","guid":{"rendered":"https:\/\/idiscam.es\/investigacion\/clinical-research-group-applied-to-diagnostic-imaging-icadi\/"},"modified":"2024-04-09T09:33:06","modified_gmt":"2024-04-09T09:33:06","slug":"clinical-research-group-applied-to-diagnostic-imaging-icadi","status":"publish","type":"investigacion","link":"https:\/\/idiscam.es\/en\/investigacion\/clinical-research-group-applied-to-diagnostic-imaging-icadi\/","title":{"rendered":"CLINICAL RESEARCH GROUP APPLIED TO DIAGNOSTIC IMAGING (ICADI)"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h1&#8243; text_color=&#8221;#1a1a19&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;CRO2022-015&#8243; font_size_phone=&#8221;25px&#8221;][\/split_line_heading][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h1&#8243; text_color=&#8221;#1a1a19&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;CLINICAL RESEARCH GROUP APPLIED TO DIAGNOSTIC IMAGING (ICADI)&#8221; font_size_phone=&#8221;25px&#8221;][\/split_line_heading][vc_column_text el_class=&#8221;text-sub-bl&#8221;]\n<h3><span style=\"color: #f77272;\">Area of chronic diseases and cancer<\/span><\/h3>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height_phone=&#8221;0&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;50px&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;column_reverse&#8221; column_direction_phone=&#8221;column_reverse&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;7\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][toggles style=&#8221;minimal&#8221; accordion=&#8221;true&#8221; accordion_starting_functionality=&#8221;closed&#8221;][toggle color=&#8221;Default&#8221; heading_tag=&#8221;h3&#8243; heading_tag_functionality=&#8221;change_html_tag&#8221; title=&#8221;Objectives and lines of research&#8221;]<div class=\"nectar-fancy-ul\" data-list-icon=\"icon-salient-thin-line\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"accent-color\" data-spacing=\"10px\" data-alignment=\"left\"> &#8211; Diagnostic imaging, especially for early detection of breast cancer.<br \/>\n&#8211; New emerging medical imaging techniques (microwave imaging), artificial intelligence, application of radiomics and optimization of clinical imaging circuits within the hospital.<br \/>\n&#8211; 3D printing and BIG data analysis to detect breast cancer risk patterns and perform personalized screening. <\/div>[\/toggle][toggle color=&#8221;Default&#8221; heading_tag=&#8221;h3&#8243; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Research team&#8221;]<div class=\"nectar-fancy-ul\" data-list-icon=\"icon-salient-thin-line\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"accent-color\" data-spacing=\"10px\" data-alignment=\"left\"> \n<ul>\n<li>CRISTINA ROMERO CASTELLANO<\/li>\n<li>LINA MARCELA CRUZ HERN\u00c1NDEZ<\/li>\n<li>PAUL MART\u00cdN AGUILAR ANGULO<\/li>\n<li>PILAR S\u00c1NCHEZ-CAMACHO GONZ\u00c1LEZ-CARRATO<\/li>\n<li>RUB\u00c9N GIOVANETTI GONZ\u00c1LEZ<\/li>\n<li>ANA RODR\u00cdGUEZ S\u00c1NCHEZ<\/li>\n<li>DANIEL \u00c1LVAREZ S\u00c1NCHEZ-BAYUELA<\/li>\n<\/ul>\n <\/div>[\/toggle][toggle color=&#8221;Default&#8221; heading_tag=&#8221;h3&#8243; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Projects&#8221;]<div class=\"nectar-fancy-ul\" data-list-icon=\"icon-salient-thin-line\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"accent-color\" data-spacing=\"10px\" data-alignment=\"left\"> \n<div id=\"gtx-trans\" style=\"position: absolute; left: 5px; top: -10px;\">\n<div class=\"gtx-trans-icon\"><\/div>\n<\/div>\n <\/div>[vc_column_text][\/vc_column_text][\/toggle][toggle color=&#8221;Default&#8221; heading_tag=&#8221;default&#8221; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Publications&#8221;]<div class=\"nectar-fancy-ul\" data-list-icon=\"icon-salient-thin-line\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"accent-color\" data-spacing=\"10px\" data-alignment=\"left\">  <\/div>[vc_column_text][\/vc_column_text][\/toggle][toggle color=&#8221;Default&#8221; heading_tag=&#8221;default&#8221; heading_tag_functionality=&#8221;default&#8221; title=&#8221;Group website&#8221;]<div class=\"nectar-fancy-ul\" data-list-icon=\"icon-salient-thin-line\" data-animation=\"false\" data-animation-delay=\"0\" data-color=\"accent-color\" data-spacing=\"10px\" data-alignment=\"left\">  <\/div>[vc_column_text][\/vc_column_text][\/toggle][\/toggles][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;5\/12&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;small_depth&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1683028189724{margin-bottom: -5px !important;}&#8221;]Responsible[\/vc_column_text][divider line_type=&#8221;Small Line&#8221; line_alignment=&#8221;default&#8221; line_thickness=&#8221;2&#8243; divider_color=&#8221;extra-color-2&#8243; custom_height=&#8221;20&#8243; custom_line_width=&#8221;90&#8243;][vc_column_text]<strong>CRISTINA ROMERO CASTELLANO<\/strong>[\/vc_column_text][vc_column_text]<strong><a href=\"mailto:cromeroc@sescam.jccm.es\">cromeroc@sescam.jccm.es<\/a><\/strong>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;small_depth&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1689772433255{margin-bottom: -5px !important;}&#8221;]IP[\/vc_column_text][divider line_type=&#8221;Small Line&#8221; line_alignment=&#8221;default&#8221; line_thickness=&#8221;2&#8243; divider_color=&#8221;extra-color-2&#8243; custom_height=&#8221;20&#8243; custom_line_width=&#8221;90&#8243;][vc_column_text]<b>CRISTINA ROMERO CASTELLANO<\/b>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_global_section id=&#8221;15&#8243;][\/vc_column][\/vc_row]\n","protected":false},"featured_media":0,"template":"","categories":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CLINICAL RESEARCH GROUP APPLIED TO DIAGNOSTIC IMAGING (ICADI) - Instituto de Investigaci\u00f3n Sanitaria de CLM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/idiscam.es\/en\/investigacion\/clinical-research-group-applied-to-diagnostic-imaging-icadi\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CLINICAL RESEARCH GROUP APPLIED TO DIAGNOSTIC IMAGING (ICADI) - Instituto de Investigaci\u00f3n Sanitaria de CLM\" \/>\n<meta property=\"og:description\" content=\"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h1&#8243; text_color=&#8221;#1a1a19&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;CRO2022-015&#8243;...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/idiscam.es\/en\/investigacion\/clinical-research-group-applied-to-diagnostic-imaging-icadi\/\" \/>\n<meta property=\"og:site_name\" content=\"Instituto de Investigaci\u00f3n Sanitaria de CLM\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-09T09:33:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/idiscam.es\/en\/investigacion\/clinical-research-group-applied-to-diagnostic-imaging-icadi\/\",\"url\":\"https:\/\/idiscam.es\/en\/investigacion\/clinical-research-group-applied-to-diagnostic-imaging-icadi\/\",\"name\":\"CLINICAL RESEARCH GROUP APPLIED TO DIAGNOSTIC IMAGING (ICADI) - Instituto de Investigaci\u00f3n Sanitaria de CLM\",\"isPartOf\":{\"@id\":\"https:\/\/idiscam.es\/en\/#website\"},\"datePublished\":\"2023-07-18T07:41:53+00:00\",\"dateModified\":\"2024-04-09T09:33:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/idiscam.es\/en\/investigacion\/clinical-research-group-applied-to-diagnostic-imaging-icadi\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/idiscam.es\/en\/investigacion\/clinical-research-group-applied-to-diagnostic-imaging-icadi\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/idiscam.es\/en\/investigacion\/clinical-research-group-applied-to-diagnostic-imaging-icadi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/idiscam.es\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CLINICAL RESEARCH GROUP APPLIED TO DIAGNOSTIC IMAGING (ICADI)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/idiscam.es\/en\/#website\",\"url\":\"https:\/\/idiscam.es\/en\/\",\"name\":\"Instituto de Investigaci\u00f3n Sanitaria de CLM\",\"description\":\"IDISCAM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/idiscam.es\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CLINICAL RESEARCH GROUP APPLIED TO DIAGNOSTIC IMAGING (ICADI) - Instituto de Investigaci\u00f3n Sanitaria de CLM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/idiscam.es\/en\/investigacion\/clinical-research-group-applied-to-diagnostic-imaging-icadi\/","og_locale":"en_US","og_type":"article","og_title":"CLINICAL RESEARCH GROUP APPLIED TO DIAGNOSTIC IMAGING (ICADI) - Instituto de Investigaci\u00f3n Sanitaria de CLM","og_description":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h1&#8243; text_color=&#8221;#1a1a19&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;CRO2022-015&#8243;...","og_url":"https:\/\/idiscam.es\/en\/investigacion\/clinical-research-group-applied-to-diagnostic-imaging-icadi\/","og_site_name":"Instituto de Investigaci\u00f3n Sanitaria de CLM","article_modified_time":"2024-04-09T09:33:06+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/idiscam.es\/en\/investigacion\/clinical-research-group-applied-to-diagnostic-imaging-icadi\/","url":"https:\/\/idiscam.es\/en\/investigacion\/clinical-research-group-applied-to-diagnostic-imaging-icadi\/","name":"CLINICAL RESEARCH GROUP APPLIED TO DIAGNOSTIC IMAGING (ICADI) - Instituto de Investigaci\u00f3n Sanitaria de CLM","isPartOf":{"@id":"https:\/\/idiscam.es\/en\/#website"},"datePublished":"2023-07-18T07:41:53+00:00","dateModified":"2024-04-09T09:33:06+00:00","breadcrumb":{"@id":"https:\/\/idiscam.es\/en\/investigacion\/clinical-research-group-applied-to-diagnostic-imaging-icadi\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/idiscam.es\/en\/investigacion\/clinical-research-group-applied-to-diagnostic-imaging-icadi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/idiscam.es\/en\/investigacion\/clinical-research-group-applied-to-diagnostic-imaging-icadi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/idiscam.es\/en\/"},{"@type":"ListItem","position":2,"name":"CLINICAL RESEARCH GROUP APPLIED TO DIAGNOSTIC IMAGING (ICADI)"}]},{"@type":"WebSite","@id":"https:\/\/idiscam.es\/en\/#website","url":"https:\/\/idiscam.es\/en\/","name":"Instituto de Investigaci\u00f3n Sanitaria de CLM","description":"IDISCAM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/idiscam.es\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/idiscam.es\/en\/wp-json\/wp\/v2\/investigacion\/2436"}],"collection":[{"href":"https:\/\/idiscam.es\/en\/wp-json\/wp\/v2\/investigacion"}],"about":[{"href":"https:\/\/idiscam.es\/en\/wp-json\/wp\/v2\/types\/investigacion"}],"wp:attachment":[{"href":"https:\/\/idiscam.es\/en\/wp-json\/wp\/v2\/media?parent=2436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/idiscam.es\/en\/wp-json\/wp\/v2\/categories?post=2436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}